{"id":7744,"date":"2025-08-29T16:57:06","date_gmt":"2025-08-29T14:57:06","guid":{"rendered":"https:\/\/b19.be\/galerie\/b19-brussels-afterwork-arnaud-feist\/"},"modified":"2025-08-29T16:57:06","modified_gmt":"2025-08-29T14:57:06","slug":"b19-brussels-afterwork-arnaud-feist","status":"publish","type":"gallery","link":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/","title":{"rendered":"B19 Brussels \u2013 Afterwork \u2013 Arnaud Feist"},"content":{"rendered":"<p><span>Arnaud Feist : \u00ab Ce n\u2019est pas facile de red\u00e9marrer apr\u00e8s une crise mais nous sommes pr\u00eats \u00bb <\/span><\/p>\n<p><span>Apr\u00e8s une ann\u00e9e 2019 \u00ab record \u00bb avec plus de 26 millions de passagers, Brussel Airport a connu une longue ann\u00e9e de crise Covid qui a engendr\u00e9 une perte estim\u00e9e \u00e0 150 millions d\u2019euros. <\/span><\/p>\n<p><span>Arnaud Feist ne s\u2019est pas d\u00e9mobilis\u00e9 et l\u2019a\u00e9roport est aujourd\u2019hui pr\u00eat \u00e0 rebondir dans des conditions sanitaires toujours difficiles mais parfaitement accompagn\u00e9es et sous contr\u00f4le. <\/span><\/p>\n<p><span>Lui qui a connu 6 ministres de la Mobilit\u00e9 en 12 ans \u00e0 la t\u00eate de Brussels Airport continue \u00e0 miser sur l\u2019avenir d\u2019un a\u00e9roport \u00e0 taille humaine qui travaille sans rel\u00e2che sur l\u2019am\u00e9lioration constante de<br \/>\u00ab l\u2019exp\u00e9rience client \u00bb : \u00ab La valeur humaine est encore plus essentielle en temps de crise. Nous travaillons sur de nouvelles lignes, un meilleur acc\u00e8s et une plus grande connectivit\u00e9. L\u2019impact carbone est \u00e9galement une de nos pr\u00e9occupations majeures. Pour cela, il faudrait \u00e9galement une vision politique plus claire en mati\u00e8re de mobilit\u00e9 et une profonde volont\u00e9 de r\u00e9former notre complexit\u00e9 institutionnelle\u2026 nous souffrons d\u2019un handicap certain de visibilit\u00e9 et d\u2019efficacit\u00e9 au niveau du tourisme \u00bb. <\/span><\/p>\n<p><span>Un contexte f\u00e9d\u00e9ral sur lequel vient se greffer une concurrence internationale f\u00e9roce et une cohabitation perfectible sur le plan national m\u00eame si le leadership de Brussels Airport reste incontestable par<br \/>rapport \u00e0 Charleroi et Li\u00e8ge : \u00ab Nous avons eu des opportunit\u00e9s un peu galvaud\u00e9es avec Charleroi mais je reste persuad\u00e9 que des synergies intelligentes son possibles\u2026 \u00bb <\/span><\/p>\n<p><span>Avec un CEO entreprenant et un actionnariat stable (dont 25% sont encore d\u00e9tenu par L\u2019Etat), l\u2019optimisme peut rester de mise dans ce v\u00e9ritable \u00e9cosyst\u00e8me qui emploie 24 000 personnes et g\u00e9n\u00e8re 40 000 d\u00e9bouch\u00e9s indirects !  <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arnaud Feist : \u00ab Ce n\u2019est pas facile de red\u00e9marrer apr\u00e8s une crise mais nous sommes pr\u00eats \u00bb Apr\u00e8s une ann\u00e9e 2019 \u00ab record \u00bb avec plus de 26 millions de passagers, Brussel Airport a connu une longue ann\u00e9e de crise Covid qui a engendr\u00e9 une perte estim\u00e9e \u00e0 150 millions d\u2019euros. Arnaud Feist ne [&hellip;]<\/p>\n","protected":false},"featured_media":7745,"template":"","class_list":["post-7744","gallery","type-gallery","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B19 Brussels - Afterwork - Arnaud Feist - B19<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B19 Brussels - Afterwork - Arnaud Feist - B19\" \/>\n<meta property=\"og:description\" content=\"Arnaud Feist : \u00ab Ce n\u2019est pas facile de red\u00e9marrer apr\u00e8s une crise mais nous sommes pr\u00eats \u00bb Apr\u00e8s une ann\u00e9e 2019 \u00ab record \u00bb avec plus de 26 millions de passagers, Brussel Airport a connu une longue ann\u00e9e de crise Covid qui a engendr\u00e9 une perte estim\u00e9e \u00e0 150 millions d\u2019euros. Arnaud Feist ne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/\" \/>\n<meta property=\"og:site_name\" content=\"B19\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/B19BusinessClub\" \/>\n<meta property=\"og:image\" content=\"https:\/\/b19.be\/wp-content\/uploads\/2023\/09\/b19-national-business-club.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/\",\"url\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/\",\"name\":\"B19 Brussels - Afterwork - Arnaud Feist - B19\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/b19.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg\",\"datePublished\":\"2025-08-29T14:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/#primaryimage\",\"url\":\"https:\\\/\\\/b19.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg\",\"contentUrl\":\"https:\\\/\\\/b19.be\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg\",\"width\":2239,\"height\":1490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/galerie\\\/b19-brussels-afterwork-arnaud-feist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/b19.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B19 Brussels \u2013 Afterwork \u2013 Arnaud Feist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/b19.be\\\/nl\\\/\",\"name\":\"B19\",\"description\":\"National Business Club &amp; Networking\",\"publisher\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#organization\"},\"alternateName\":\"B19 Business Club\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/b19.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#organization\",\"name\":\"B19\",\"alternateName\":\"B19 Business Club\",\"url\":\"https:\\\/\\\/b19.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/b19.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logob19.svg\",\"contentUrl\":\"https:\\\/\\\/b19.be\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logob19.svg\",\"width\":1,\"height\":1,\"caption\":\"B19\"},\"image\":{\"@id\":\"https:\\\/\\\/b19.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/B19BusinessClub\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/b19-country-club\\\/\",\"https:\\\/\\\/www.instagram.com\\\/b19_business_club\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B19 Brussels - Afterwork - Arnaud Feist - B19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/","og_locale":"nl_BE","og_type":"article","og_title":"B19 Brussels - Afterwork - Arnaud Feist - B19","og_description":"Arnaud Feist : \u00ab Ce n\u2019est pas facile de red\u00e9marrer apr\u00e8s une crise mais nous sommes pr\u00eats \u00bb Apr\u00e8s une ann\u00e9e 2019 \u00ab record \u00bb avec plus de 26 millions de passagers, Brussel Airport a connu une longue ann\u00e9e de crise Covid qui a engendr\u00e9 une perte estim\u00e9e \u00e0 150 millions d\u2019euros. Arnaud Feist ne [&hellip;]","og_url":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/","og_site_name":"B19","article_publisher":"https:\/\/www.facebook.com\/B19BusinessClub","og_image":[{"width":2000,"height":1331,"url":"https:\/\/b19.be\/wp-content\/uploads\/2023\/09\/b19-national-business-club.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/","url":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/","name":"B19 Brussels - Afterwork - Arnaud Feist - B19","isPartOf":{"@id":"https:\/\/b19.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/#primaryimage"},"image":{"@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/#primaryimage"},"thumbnailUrl":"https:\/\/b19.be\/wp-content\/uploads\/2025\/08\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg","datePublished":"2025-08-29T14:57:06+00:00","breadcrumb":{"@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/#primaryimage","url":"https:\/\/b19.be\/wp-content\/uploads\/2025\/08\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg","contentUrl":"https:\/\/b19.be\/wp-content\/uploads\/2025\/08\/293b12fe-8bd1-4c84-93c0-23c2d273f50d.jpg","width":2239,"height":1490},{"@type":"BreadcrumbList","@id":"https:\/\/b19.be\/nl\/galerie\/b19-brussels-afterwork-arnaud-feist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/b19.be\/nl\/"},{"@type":"ListItem","position":2,"name":"B19 Brussels \u2013 Afterwork \u2013 Arnaud Feist"}]},{"@type":"WebSite","@id":"https:\/\/b19.be\/nl\/#website","url":"https:\/\/b19.be\/nl\/","name":"B19","description":"National Business Club &amp; Networking","publisher":{"@id":"https:\/\/b19.be\/nl\/#organization"},"alternateName":"B19 Business Club","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/b19.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/b19.be\/nl\/#organization","name":"B19","alternateName":"B19 Business Club","url":"https:\/\/b19.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/b19.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/b19.be\/wp-content\/uploads\/2023\/09\/logob19.svg","contentUrl":"https:\/\/b19.be\/wp-content\/uploads\/2023\/09\/logob19.svg","width":1,"height":1,"caption":"B19"},"image":{"@id":"https:\/\/b19.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/B19BusinessClub","https:\/\/www.linkedin.com\/company\/b19-country-club\/","https:\/\/www.instagram.com\/b19_business_club\/"]}]}},"_links":{"self":[{"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/gallery\/7744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/types\/gallery"}],"version-history":[{"count":0,"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/gallery\/7744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/media\/7745"}],"wp:attachment":[{"href":"https:\/\/b19.be\/nl\/wp-json\/wp\/v2\/media?parent=7744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}